{"id":206695,"date":"2024-09-28T14:31:52","date_gmt":"2024-09-28T14:31:52","guid":{"rendered":"https:\/\/www.mountaindropoffs.com\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/"},"modified":"2025-06-04T10:55:21","modified_gmt":"2025-06-04T10:55:21","slug":"festival-de-vtt-de-la-passportes-du-soleil-2025","status":"publish","type":"event_cpt","link":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/","title":{"rendered":"Festival de VTT de la Pass&rsquo;Portes du Soleil 2025"},"content":{"rendered":"","protected":false},"featured_media":248071,"template":"","class_list":["post-206695","event_cpt","type-event_cpt","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival de VTT de la Pass&#039;Portes du Soleil 2025 - Mountain Dropoffs<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l&#039;\u00e9dition 2025 du week-end v\u00e9lo de la Pass&#039;Portes du Soleil et comment vous inscrire !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival de VTT de la Pass&#039;Portes du Soleil 2025 - Mountain Dropoffs\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l&#039;\u00e9dition 2025 du week-end v\u00e9lo de la Pass&#039;Portes du Soleil et comment vous inscrire !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Mountain Dropoffs\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T10:55:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mountaindropoffs.com\/wp-content\/uploads\/2024\/09\/pass-portes-vtt-2025.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/\",\"url\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/\",\"name\":\"Festival de VTT de la Pass'Portes du Soleil 2025 - Mountain Dropoffs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pass-portes-vtt-2025.webp\",\"datePublished\":\"2024-09-28T14:31:52+00:00\",\"dateModified\":\"2025-06-04T10:55:21+00:00\",\"description\":\"D\u00e9couvrez l'\u00e9dition 2025 du week-end v\u00e9lo de la Pass'Portes du Soleil et comment vous inscrire !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pass-portes-vtt-2025.webp\",\"contentUrl\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/pass-portes-vtt-2025.webp\",\"width\":860,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/event\\\/festival-de-vtt-de-la-passportes-du-soleil-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival de VTT de la Pass&#8217;Portes du Soleil 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/\",\"name\":\"Mountain Dropoffs\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mountaindropoffs.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival de VTT de la Pass'Portes du Soleil 2025 - Mountain Dropoffs","description":"D\u00e9couvrez l'\u00e9dition 2025 du week-end v\u00e9lo de la Pass'Portes du Soleil et comment vous inscrire !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Festival de VTT de la Pass'Portes du Soleil 2025 - Mountain Dropoffs","og_description":"D\u00e9couvrez l'\u00e9dition 2025 du week-end v\u00e9lo de la Pass'Portes du Soleil et comment vous inscrire !","og_url":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/","og_site_name":"Mountain Dropoffs","article_modified_time":"2025-06-04T10:55:21+00:00","og_image":[{"width":860,"height":484,"url":"https:\/\/www.mountaindropoffs.com\/wp-content\/uploads\/2024\/09\/pass-portes-vtt-2025.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/","url":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/","name":"Festival de VTT de la Pass'Portes du Soleil 2025 - Mountain Dropoffs","isPartOf":{"@id":"https:\/\/www.mountaindropoffs.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mountaindropoffs.com\/wp-content\/uploads\/2024\/09\/pass-portes-vtt-2025.webp","datePublished":"2024-09-28T14:31:52+00:00","dateModified":"2025-06-04T10:55:21+00:00","description":"D\u00e9couvrez l'\u00e9dition 2025 du week-end v\u00e9lo de la Pass'Portes du Soleil et comment vous inscrire !","breadcrumb":{"@id":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/#primaryimage","url":"https:\/\/www.mountaindropoffs.com\/wp-content\/uploads\/2024\/09\/pass-portes-vtt-2025.webp","contentUrl":"https:\/\/www.mountaindropoffs.com\/wp-content\/uploads\/2024\/09\/pass-portes-vtt-2025.webp","width":860,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/www.mountaindropoffs.com\/fr\/event\/festival-de-vtt-de-la-passportes-du-soleil-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mountaindropoffs.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Festival de VTT de la Pass&#8217;Portes du Soleil 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.mountaindropoffs.com\/fr\/#website","url":"https:\/\/www.mountaindropoffs.com\/fr\/","name":"Mountain Dropoffs","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mountaindropoffs.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.mountaindropoffs.com\/fr\/wp-json\/wp\/v2\/event_cpt\/206695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mountaindropoffs.com\/fr\/wp-json\/wp\/v2\/event_cpt"}],"about":[{"href":"https:\/\/www.mountaindropoffs.com\/fr\/wp-json\/wp\/v2\/types\/event_cpt"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mountaindropoffs.com\/fr\/wp-json\/wp\/v2\/media\/248071"}],"wp:attachment":[{"href":"https:\/\/www.mountaindropoffs.com\/fr\/wp-json\/wp\/v2\/media?parent=206695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}